{"id":56,"count":1,"description":"","link":"https:\/\/www.papillonintimo.it\/sito\/categoria-prodotto\/papillon-home\/","name":"PAPILLON HOME","slug":"papillon-home","taxonomy":"product_cat","parent":0,"meta":[],"menu_order":0,"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>PAPILLON HOME Archivi - Papillon Factory Outlet<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.papillonintimo.it\/sito\/categoria-prodotto\/papillon-home\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"PAPILLON HOME Archivi - Papillon Factory Outlet\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.papillonintimo.it\/sito\/categoria-prodotto\/papillon-home\/\" \/>\n<meta property=\"og:site_name\" content=\"Papillon Factory Outlet\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/www.papillonintimo.it\\\/sito\\\/categoria-prodotto\\\/papillon-home\\\/\",\"url\":\"https:\\\/\\\/www.papillonintimo.it\\\/sito\\\/categoria-prodotto\\\/papillon-home\\\/\",\"name\":\"PAPILLON HOME Archivi - Papillon Factory Outlet\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.papillonintimo.it\\\/sito\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.papillonintimo.it\\\/sito\\\/categoria-prodotto\\\/papillon-home\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.papillonintimo.it\\\/sito\\\/categoria-prodotto\\\/papillon-home\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.papillonintimo.it\\\/sito\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"PAPILLON HOME\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.papillonintimo.it\\\/sito\\\/#website\",\"url\":\"https:\\\/\\\/www.papillonintimo.it\\\/sito\\\/\",\"name\":\"Papillon Factory Outlet\",\"description\":\"Papillon Official\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.papillonintimo.it\\\/sito\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.papillonintimo.it\\\/sito\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.papillonintimo.it\\\/sito\\\/#organization\",\"name\":\"Papillon Factory Outlet\",\"url\":\"https:\\\/\\\/www.papillonintimo.it\\\/sito\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.papillonintimo.it\\\/sito\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.papillonintimo.it\\\/sito\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/intimo-1.png\",\"contentUrl\":\"https:\\\/\\\/www.papillonintimo.it\\\/sito\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/intimo-1.png\",\"width\":374,\"height\":89,\"caption\":\"Papillon Factory Outlet\"},\"image\":{\"@id\":\"https:\\\/\\\/www.papillonintimo.it\\\/sito\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"PAPILLON HOME Archivi - Papillon Factory Outlet","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.papillonintimo.it\/sito\/categoria-prodotto\/papillon-home\/","og_locale":"it_IT","og_type":"article","og_title":"PAPILLON HOME Archivi - Papillon Factory Outlet","og_url":"https:\/\/www.papillonintimo.it\/sito\/categoria-prodotto\/papillon-home\/","og_site_name":"Papillon Factory Outlet","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.papillonintimo.it\/sito\/categoria-prodotto\/papillon-home\/","url":"https:\/\/www.papillonintimo.it\/sito\/categoria-prodotto\/papillon-home\/","name":"PAPILLON HOME Archivi - Papillon Factory Outlet","isPartOf":{"@id":"https:\/\/www.papillonintimo.it\/sito\/#website"},"breadcrumb":{"@id":"https:\/\/www.papillonintimo.it\/sito\/categoria-prodotto\/papillon-home\/#breadcrumb"},"inLanguage":"it-IT"},{"@type":"BreadcrumbList","@id":"https:\/\/www.papillonintimo.it\/sito\/categoria-prodotto\/papillon-home\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.papillonintimo.it\/sito\/"},{"@type":"ListItem","position":2,"name":"PAPILLON HOME"}]},{"@type":"WebSite","@id":"https:\/\/www.papillonintimo.it\/sito\/#website","url":"https:\/\/www.papillonintimo.it\/sito\/","name":"Papillon Factory Outlet","description":"Papillon Official","publisher":{"@id":"https:\/\/www.papillonintimo.it\/sito\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.papillonintimo.it\/sito\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.papillonintimo.it\/sito\/#organization","name":"Papillon Factory Outlet","url":"https:\/\/www.papillonintimo.it\/sito\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.papillonintimo.it\/sito\/#\/schema\/logo\/image\/","url":"https:\/\/www.papillonintimo.it\/sito\/wp-content\/uploads\/2020\/11\/intimo-1.png","contentUrl":"https:\/\/www.papillonintimo.it\/sito\/wp-content\/uploads\/2020\/11\/intimo-1.png","width":374,"height":89,"caption":"Papillon Factory Outlet"},"image":{"@id":"https:\/\/www.papillonintimo.it\/sito\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.papillonintimo.it\/sito\/wp-json\/wp\/v2\/product_cat\/56","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.papillonintimo.it\/sito\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/www.papillonintimo.it\/sito\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"wp:post_type":[{"href":"https:\/\/www.papillonintimo.it\/sito\/wp-json\/wp\/v2\/product?product_cat=56"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}